{"id":2863,"date":"2021-03-11T13:55:12","date_gmt":"2021-03-11T11:55:12","guid":{"rendered":"http:\/\/vetus.inlinedigital.nl\/cms\/innovation-at-vetus\/"},"modified":"2022-03-22T13:44:56","modified_gmt":"2022-03-22T12:44:56","slug":"innovatie-bij-vetus","status":"publish","type":"page","link":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/","title":{"rendered":"Innovatie"},"content":{"rendered":"\t<!-- <section class=\"section section--colored bg-light\"> -->\n\t<section class=\"section content-blocks content-blocks--colored bg-primary text-white  pt-0  \">\n\t\t\n<section id=\"content-block-12-block_602f7d39d3c85\" class=\"section content-block content-block--colored content-block--colored-2 bg-primary text-white \">\n    <div class=\"content-block__background\"><\/div>\n\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center\">\n            <div class=\"col-md-6 col-lg-6\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio\">\n                            <div class=\"media__wrapper media__wrapper--colored\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_hoofdfoto-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4 offset-lg-1\">\n                <div class=\"content-block__body\">\n                                            <h3 class=\"content-block__title\">\n                            Innovatie                        <\/h3>\n                                                                                    <p>Innovatieve producten ontwerpen is een belangrijk onderdeel van de bedrijfsfilosofie. Onze missie is om producten te maken, die u het leven aan boord gemakkelijk maken. Creatief, energiek en altijd met een glimlach.<\/p>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\t<\/section>\n\t\n\n\n<section class=\"section  \">\n    \n\n<section id=\"section-text-block-block_602f7d84d3c88\" class=\"section text-block \">\n            <div class=\"section__header text-center\">\n            <div class=\"container\">\n                <div class=\"row\">\n                    <div class=\"col-lg-6 offset-lg-3\">\n                                                    <h3 class=\"section__title\">\n                                Het innovatieproces                            <\/h3>\n                                                                            <div class=\"section__intro text-lg\">\n                                <p>\n                                    Van idee tot product. Het gebeurt allemaal in eigen huis.                                <\/p>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"section__body\">\n            <div class=\"text-block__image \">\n                <div class=\"container\">\n                    <div class=\"row\">\n                        <div class=\"col-lg-12\">\n                            <div class=\"media media--clipped ratio ratio--long\">\n                                <div class=\"media__wrapper media__wrapper--colored\">\n                                    <img decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_innovation-process-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 670px, (max-width: 991.98px) 930px, (max-width: 1279.98px) 670px, (max-width: 1899.98px) 930px, 1170px\" loading=\"lazy\" \/>                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        <\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center flex-md-row-reverse\">\n            <div class=\"col-md-6 col-lg-7 offset-lg-1\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"518\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-300x225.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-1024x768.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-768x576.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-418x314.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-604x453.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-2-building_eline-970x728.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4\">\n                <div class=\"content-block__body\">\n                    \n                                            <h2 class=\"content-block__title\">\n                            Creator of boat systems                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Sinds de oprichting in 1964 heeft VETUS zich ontwikkeld tot een toonaangevend bedrijf op het gebied van innovatieve producten voor de pleziervaart en kleine beroepsvaart.                            <\/p>\n                        <\/div>\n                    \n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center\">\n            <div class=\"col-md-6 col-lg-7\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step1-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4 offset-lg-1\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 1                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Het idee                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Op basis van input van gebruikers, marktonderzoek en nieuwe beschikbare innovaties wordt een idee geboren.                            <\/p>\n                        <\/div>\n                    \n                                            <p>Alle informatie wordt samengebracht in ons platform &#8216;VETUS design lab&#8217;. Samen met partners uit de industrie, overheid en de aanwezige kennisinstellingen zoals universiteiten, gaan onze ingenieurs aan de slag met de ontwikkeling van nieuwe producten.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center flex-md-row-reverse\">\n            <div class=\"col-md-6 col-lg-7 offset-lg-1\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step2-3d-printer-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 2                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Het concept                         <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Wanneer er een idee is voor een product, wordt er een eerste concept ontworpen.                            <\/p>\n                        <\/div>\n                    \n                                            <p>Alle concepten worden intern en met een geselecteerd team van gebruikers besproken. We gebruiken in-house 3D-printing om tastbare modellen te maken die kunnen worden besproken.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center\">\n            <div class=\"col-md-6 col-lg-7\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step3-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4 offset-lg-1\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 3                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            De uitvoering van het product                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Aan de hand van de marktfeedback wordt een lijst van productvereisten opgesteld.                             <\/p>\n                        <\/div>\n                    \n                                            <p>In deze lijst zijn belangrijke punten opgenomen, zoals installatiegemak, robuuste kwaliteit, betrouwbaarheid en veiligheid. Met de laatste 3D Computer Aided Design programma&#8217;s worden de concepttekeningen door onze ingenieurs uitgewerkt tot technische tekeningen. Afmetingen en toleranties worden hierop afgestemd om een perfecte pasvorm en hoogwaardige afwerking te garanderen.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center flex-md-row-reverse\">\n            <div class=\"col-md-6 col-lg-7 offset-lg-1\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"518\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-300x225.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-1024x768.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-768x576.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-418x314.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-604x453.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/innovation_assembling_eline_2-970x728.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 4                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Productie                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Onze ingenieurs werken samen met verschillende gespecialiseerde productiepartners die experts zijn op hun gebied.                            <\/p>\n                        <\/div>\n                    \n                                            <p>Door samen te werken wordt de hoogste kwaliteit gegarandeerd. Natuurlijk maken wij ook zeer gedetailleerde product- en installatie-instructies voor onze producten.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center\">\n            <div class=\"col-md-6 col-lg-7\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/innovation-manual_eline-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4 offset-lg-1\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 5                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Installatie- en gebruikershandleiding                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Geen enkel nieuw product verlaat het VETUS magazijn zonder een uitgebreide en zeer gedetailleerde product- en installatiehandleiding.                            <\/p>\n                        <\/div>\n                    \n                                            <p>Een aparte afdeling zorgt ervoor dat booteigenaren hun VETUS producten zo goed mogelijk gebruiken. Ons team voor technische documentatie is er vanaf het begin bij betrokken en denkt mee tijdens het hele proces, zodat niet alleen de installatie, maar ook het gebruiksgemak en onderhoud aan bod komen.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center flex-md-row-reverse\">\n            <div class=\"col-md-6 col-lg-7 offset-lg-1\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/Innovation_step6-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 6                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Testfase                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Een product in een maritieme omgeving moet moeiteloos bestand zijn tegen zware omstandigheden.                             <\/p>\n                        <\/div>\n                    \n                                            <p>Daarom worden alle producten aan een reeks tests onderworpen om er zeker van te zijn dat zij aan onze hoge kwaliteitsnormen voldoen (weersinvloeden, UV-tests, zoutsproei). De tests worden zowel in onze eigen testfaciliteit als door onafhankelijke test- en certificeringsdeskundigen uitgevoerd.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section id=\"content-block-7block_602f7d84d3c88\" class=\"section content-block content-block--image content-block--logo \">\n    <div class=\"container\">\n        <div class=\"row d-flex align-items-center\">\n            <div class=\"col-md-6 col-lg-7\">\n                                    <div class=\"content-block__visuals\">\n                        <div class=\"content-block__media media media--clipped ratio bg-light\">\n                            <a href=\"#\" title=\"\" target=\"\" class=\"media__wrapper\">\n                                <img decoding=\"async\" width=\"690\" height=\"460\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7.jpg 1200w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/website-mockup_step7-970x647.jpg 970w\" sizes=\"auto, (max-width: 575.98px) 431px, (max-width: 767.98px) 530px, (max-width: 991.98px) 330px, (max-width: 1279.98px) 530px, (max-width: 1899.98px) 690px, 930px\" loading=\"lazy\" \/>                            <\/a>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"col-md-6 col-lg-4 offset-lg-1\">\n                <div class=\"content-block__body\">\n                                            <div class=\"content-block__label badge  text-overline\">\n                            Stap 7                        <\/div>\n                    \n                                            <h2 class=\"content-block__title\">\n                            Marktintroductie                        <\/h2>\n                    \n                                            <div class=\"content-block__intro\">\n                            <p>\n                                Wanneer het product in de rekken van het VETUS-magazijn ligt, is het gereed om op de markt te worden gebracht. \r\n                            <\/p>\n                        <\/div>\n                    \n                                            <p>Wij zijn trots op ons wereldwijde netwerk dat vanaf de start van ons bedrijf sterk is ontwikkeld. Het is via deze kanalen dat producten internationaal ge\u00efntroduceerd worden in de lokale markten en natuurlijk via bootshows, onze website en social media kanalen.<\/p>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/section>\n\n\n\n<hr class=\"section mt-0\">\n\n<section class=\"section cards cards--default \">\n    <div class=\"section__header mb-4 cards__header\">\n        <div class=\"container d-flex flex-column flex-md-row align-items-center justify-content-center justify-content-md-between\">\n            <div class=\"d-flex align-items-center mr-md-4\">\n                                    <div class=\"section__icon\">\n                        <span class=\"btn btn-primary btn-icon-only\">\n                            <i class=\"icon icon-description\"><\/i>\n                        <\/span>\n                    <\/div>\n                \n                                    <h3 class=\"section__title cards__title\">\n                        VETUS nieuws                    <\/h3>\n                            <\/div>\n\n                            <div class=\"ml-md-auto flex-shrink-0 d-none d-md-block\">\n                    <a href=\"https:\/\/vetus.com\/nl\/nieuws\/\" class=\"btn btn-sm btn-empty btn-empty-primary\">\n                        <span>\n                            Laatste nieuws                        <\/span>\n                        <i class=\"icon icon-keyboard_arrow_right\"><\/i>\n                    <\/a>\n                <\/div>\n                    <\/div>\n    <\/div>\n            <div class=\"section__body cards__body\">\n            <div class=\"container\">\n                <div class=\"row row--col-margin-small row--col-margin-md-medium\">\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"254\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-507x254.jpeg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-507x254.jpeg 507w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-300x150.jpeg 300w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-768x384.jpeg 768w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-210x105.jpeg 210w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-330x165.jpeg 330w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-431x216.jpeg 431w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-530x265.jpeg 530w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-690x345.jpeg 690w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-930x465.jpeg 930w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2-1170x585.jpeg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/narrowboat-day-vetus-2.jpeg 1880w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 april, 2026                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-electric-narrowboat-experience-day\/\" class=\"stretched-link h5\">\n                Press Release: VETUS to host electric narrowboat experience day at the Aqueduct Marina            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-507x338.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-507x338.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-300x200.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-768x512.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-210x140.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-330x220.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-431x287.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-530x353.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-690x460.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-930x620.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate-1170x780.png 1170w, https:\/\/vetus.com\/wp-content\/uploads\/fairplaycertificate.png 1920w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 februari, 2026                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-poland-awarded-fair-play-company-certification\/\" class=\"stretched-link h5\">\n                Press release: VETUS Poland awarded prestigious Fair Play Company Certification with distinction            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"425\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-507x425.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-507x425.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-300x251.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-768x644.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-210x176.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-330x277.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-431x361.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-530x444.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-690x578.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1-930x780.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/Ontwerp-zonder-titel-1.png 940w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                9 januari, 2026                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetusmaxwell-expands\/\" class=\"stretched-link h5\">\n                Press release: VETUS MAXWELL expands team to strengthen customer support and service            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/E-Line_22000_016-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                5 januari, 2026                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-eline22kw-launch\/\" class=\"stretched-link h5\">\n                Press release &#8211; Power, Precision and Planet-Friendly Performance; the New VETUS E-LINE 22 kW            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3-1170x658.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/Sailing-La-Vagabond-3.jpg 2048w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                16 december, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-a-look-back-at-2025-with-sailing-la-vagabonde\/\" class=\"stretched-link h5\">\n                Press release &#8211; A look back at 2025 with Sailing La Vagabonde            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-507x338.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-507x338.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-300x200.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-768x512.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-210x140.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-330x220.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-431x287.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-530x353.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-690x460.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-930x620.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/nlphd4-1170x780.png 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 december, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-in-cooperation-with-nmea-vetus-extends-existing-nmea-2000-pgn-to-include-waterlock-temperature\/\" class=\"stretched-link h5\">\n                Press release &#8211; In cooperation with NMEA\u00ae, VETUS extends existing NMEA 2000\u00ae PGN to include waterlock temperature            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball-1170x658.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/sponsorship-voetball.jpg 1600w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                11 november, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-expands-local-partnerships-to-inspire-next-generation-talent-and-celebrate-maritime-heritage\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS\u00a0verdiept maatschappelijke betrokkenheid met nieuwe lokale samenwerkingen            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/metstrade-2023-overview-1-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                29 september, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-and-maxwell-set-to-connect-with-key-oems-and-stakeholders-in-europe-and-north-america\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS and Maxwell set to connect with key OEM\u2019s and stakeholders in Europe and North America            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"359\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-507x359.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-507x359.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-300x212.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-768x544.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-210x149.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-330x234.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-431x305.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-530x375.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-690x488.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-930x658.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Ferlay-Hugo_2-1170x828.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                9 september, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-appoints-new-branch-manager-to-lead-operations-in-france\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS appoints new branch manager to lead operations in France            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"380\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-507x380.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-507x380.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-300x225.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-768x576.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-210x158.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-330x248.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-431x323.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-530x398.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-690x518.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-930x698.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024-1170x878.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/Southampton-show-September-2024.jpg 2048w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                13 augustus, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-attends-autumn-boat-shows\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS attends autumn boat shows            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5-1170x780.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/PatrickHayes5.jpg 2048w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                3 juli, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-maxwell-sponsors-us-fishing-tournaments\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS Maxwell sponsors US fishing tournaments            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"676\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-507x676.jpeg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-507x676.jpeg 507w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-225x300.jpeg 225w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-768x1024.jpeg 768w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-210x280.jpeg 210w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-330x440.jpeg 330w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-431x575.jpeg 431w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-530x707.jpeg 530w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-690x920.jpeg 690w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-930x1240.jpeg 930w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-1170x1560.jpeg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/WhatsApp-Image-2025-05-13-at-16.14.07-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                5 juni, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-enhances-global-focus-on-maneuvering-systems-with-new-sales-manager\/\" class=\"stretched-link h5\">\n                Press release &#8211; VETUS Enhances Global Focus on Maneuvering Systems with New Sales Manager            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Hispania-50-Anniversary-2-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                29 april, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-hispania-celebrates-over-50-years-of-innovation-and-excellence-in-the-iberian-marine-industry\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Hispania celebrates over 50 years of innovation and excellence in the Iberian marine industry            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/5-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/5-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/5-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/5-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/5-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/5-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/5-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/5-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/5-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/5-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/5-1170x658.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                17 april, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-shares-updates-from-sv-delos-and-their-exciting-catamaran-build\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS shares updates from SV Delos and their exciting, catamaran build            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/yanmar-boot-dusseldorf24_high-res-2031-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 januari, 2025                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-previews-its-latest-electric-propulsion-solutions-at-boot-dusseldorf-2025\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS previews its latest Electric Propulsion Solutions at Boot D\u00fcsseldorf 2025            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-507x285.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-507x285.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-300x169.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-768x432.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-210x118.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-330x186.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-431x242.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-530x298.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-690x388.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-930x523.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/bowpro_and_legacy_thruster_4kres_8bit_rgb-1170x658.png 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                18 november, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-maxwell-us-and-mastry-launch-factory-backed-thruster-installation-program\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Maxwell US and Mastry Launch Factory-Backed Thruster Installation Program            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/seat-cupra.media-center-item_2-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 oktober, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-innovation-enables-cupra-terramar-car-to-set-sailfor-exclusive-americas-cup-role\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Innovation Enables CUPRA Terramar Car to Set Sail for Exclusive America\u2019s Cup Role            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/vlcsnap-2024-01-24-12h01m41s586-copy-1170x658.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                26 augustus, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-new-partnership-with-youtubers-sv-devos\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Announces New Partnership with Acclaimed Sailing YouTubers SV Delos            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Larger-version-1170x658.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                6 juni, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-inspiring-new-boat-building-venture\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS to Support Social Media Duo\u2019s Inspiring New Boat Building Venture            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"486\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-507x486.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-507x486.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-300x288.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-210x201.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-330x316.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-431x413.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1-530x508.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-1.png 655w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                28 maart, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-appoints-kevin-theuns-as-manager-sales-for-netherlands-and-belgium\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Appoints Kevin Theuns as Manager Sales for Netherlands and Belgium            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"341\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-507x341.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-507x341.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-300x202.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-768x517.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-210x141.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-330x222.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-431x290.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-530x357.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-690x465.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1-930x626.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/cat_img-e1705059991937-1170x788-1.png 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 maart, 2024                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-responds-to-customer-concerns-amidst-ongoing-economic-uncertainty\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Responds to Customer Concerns Amidst Ongoing Economic Uncertainty            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"380\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-507x380.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-507x380.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-300x225.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-768x576.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-210x158.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-330x248.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-431x323.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-530x398.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-690x518.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-930x698.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Piling-ceremony-1-1170x878.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                19 december, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-breaks-ground-on-new-headquarters\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Breaks Ground on New Headquarters            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"265\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/AD-1-507x265.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/AD-1-507x265.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-300x157.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-768x402.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-210x110.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-330x173.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-431x226.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-530x277.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-690x361.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-930x487.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1-1170x612.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/AD-1.jpg 1200w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 november, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-maxwell-marine-welcomes-new-sales-manager-for-its-superyacht-division\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Maxwell Marine Welcomes New Sales Manager for its Superyacht Division            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/deutz_en_m-line-1.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                7 november, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-d-and-m-line-diesel-engines-gain-hvo-approval\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS D and M-Line Diesel Engines Gain HVO Approval            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/VETUS-Maxwell-windlass-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                18 oktober, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-maxwell-awarded-certified-supplier-for-ibbi\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS Maxwell awarded Certified Supplier for IBBI            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Hugin-USV-on-anchor-in-front-of-Anholt-wind-farm-1170x658.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                12 oktober, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-maxwell-marine-supply-anchoring-system-for-first-usvs\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Maxwell Marine Wins Contract to Supply Anchoring System for First USVs            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"329\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-507x329.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-507x329.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-300x195.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-768x499.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-210x136.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-330x214.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-431x280.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-530x344.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-690x448.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-930x604.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/ProMot-facility-1170x760.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                19 september, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-strengthens-its-presence-in-switzerland-with-new-distributor-appointment\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS strengthens its presence in Switzerland with new distributor appointment            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Yanmar-BOOT-2023-048-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                11 september, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-autumn-boats-shows\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Autumn Boats Shows            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"400\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-507x400.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-507x400.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-300x237.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-768x606.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-210x166.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-330x260.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-431x340.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-530x418.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev-690x545.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/Vetus-Employees-3-1-rev.png 897w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                30 juni, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-boosts-global-teams\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Vetus Boosts Global Teams            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"380\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/SC-New-507x380.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/SC-New-507x380.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-300x225.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-768x576.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-210x158.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-330x248.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-431x323.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-530x398.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-690x518.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-930x698.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New-1170x878.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/SC-New.jpg 1600w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                12 mei, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-sanctuary-cove-international-boat-show\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Sanctuary Cove International Boat Show            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-507x362.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-507x362.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-300x214.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-768x549.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-210x150.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-330x236.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-431x308.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-530x379.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-690x493.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-930x664.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5-1170x836.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-5.jpg 1400w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                9 mei, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-electric-boat-show\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Electric Boat Show Italy            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5-1170x780.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/Untitled-1-5.jpg 1500w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                27 april, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-more-options-for-140-mm-tunnels\/\" class=\"stretched-link h5\">\n                Press Release &#8211; More Options For 140 mm Tunnels            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"233\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-507x233.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-507x233.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-300x138.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-768x353.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-210x97.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-330x152.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-431x198.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-530x244.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-690x317.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-930x428.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/Render-photo-new-HQ-VETUS-1170x538.png 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                21 maart, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-new-vetus-hq\/\" class=\"stretched-link h5\">\n                Press Release &#8211; New VETUS HQ            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-768x513.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-431x288.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-530x354.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-690x461.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-930x621.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/SLX54_Exterieur_41-1-1170x781.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                28 februari, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-maxwell-croatia-france-service-network\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Maxwell Croatia France Service Network            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Bertram-28CC-0704-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 februari, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-marks-50-years-in-the-us\/\" class=\"stretched-link h5\">\n                Press Release &#8211; VETUS marks 50 years in the US            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK-1170x658.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/e-air_transparent-CMYK.jpg 1920w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                23 januari, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-e-line-air\/\" class=\"stretched-link h5\">\n                Press Release &#8211; E-Line AIR            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03-1170x658.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/2021-Yamaha-F250NCB-EU-Pearl_White_SBW-Action-003-03.jpg 2000w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                20 januari, 2023                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-yamaha-vetus-partnership\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Yamaha-VETUS Partnership            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4-1170x780.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/BOW-PRO-400_4.jpg 1280w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                24 november, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-bow-pro-400\/\" class=\"stretched-link h5\">\n                Press Release &#8211; BOW PRO 400            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-507x338.jpeg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-507x338.jpeg 507w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-300x200.jpeg 300w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-768x512.jpeg 768w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-210x140.jpeg 210w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-330x220.jpeg 330w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-431x287.jpeg 431w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-530x353.jpeg 530w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-690x460.jpeg 690w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-930x620.jpeg 930w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw-1170x780.jpeg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/m7SIlhtw.jpeg 1280w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                17 augustus, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-show-overview\/\" class=\"stretched-link h5\">\n                Press Release Show Overview            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock-1170x658.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/M3kQdPCTTgW8m7A5tkoP_sydney-Adobe-Stock.jpg 1600w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                25 juli, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-sydney-boat-show\/\" class=\"stretched-link h5\">\n                Press Release Sydney Boat Show            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"324\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-507x324.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-507x324.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-300x192.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-768x491.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-210x134.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-330x211.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-431x276.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-530x339.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-690x441.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-930x595.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/Maxwell_Marine-_newwebsite_Mockup_Devices-1170x749.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 juli, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-new-maxwell-website\/\" class=\"stretched-link h5\">\n                Press Release New Maxwell Website            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-507x285.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-507x285.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-300x169.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-768x432.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-210x118.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-330x186.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-431x242.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-530x298.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-690x388.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-930x523.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/yellowv_webpage_summer_donut_kids-1170x658.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                4 juli, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-yellowv-expands-range\/\" class=\"stretched-link h5\">\n                Press Release YellowV Expands Range            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-507x338.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-507x338.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-300x200.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-768x512.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-210x140.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-330x220.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-431x287.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-530x353.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-690x460.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-930x620.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/Exhaust_VETUS_HPW_frontclose-1170x780.png 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                16 juni, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/navidurin-lloyds-register-approval\/\" class=\"stretched-link h5\">\n                NAVIDURIN\u00ae Lloyd\u2019s Register Approval            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/SCBF_2-9108250-scaled-1-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                17 mei, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/e-line-demonstration-at-sanctuary-cove\/\" class=\"stretched-link h5\">\n                E-LINE Demonstration at Sanctuary Cove            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-507x362.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-507x362.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-300x214.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-768x549.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-210x150.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-330x236.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-431x308.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-530x379.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-690x493.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-930x664.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht-1170x836.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/press-release-nieuwsbericht.jpg 1400w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 mei, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-new-website\/\" class=\"stretched-link h5\">\n                VETUS New Website            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"356\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/header-507x356.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/header-507x356.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/header-300x211.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/header-768x539.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/header-210x147.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/header-330x232.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/header-431x302.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/header-530x372.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/header-690x484.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/header-930x653.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/header-1170x821.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/header.jpg 1200w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                4 april, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/growth-and-expansion\/\" class=\"stretched-link h5\">\n                Growth and Expansion            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"407\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-507x407.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-507x407.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-300x241.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-768x617.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-210x169.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-330x265.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-431x346.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-530x426.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo-690x554.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/MJ-Sailing-FB-photo.jpg 883w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                3 maart, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/sponsordeal-mj-sailing\/\" class=\"stretched-link h5\">\n                Sponsorship M&#038;J Sailing            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-507x362.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-507x362.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-300x214.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-768x549.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-210x150.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-330x236.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-431x308.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-530x379.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-690x493.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-930x664.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-1170x836.png 1170w, https:\/\/vetus.com\/wp-content\/uploads\/eline_front_now_available-e1641826681592.png 1200w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                24 februari, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/e-line\/\" class=\"stretched-link h5\">\n                E-LINE            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-507x362.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-507x362.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-300x214.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-768x549.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-210x150.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-330x236.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-431x308.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-530x379.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-690x493.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-930x664.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full-1170x836.png 1170w, https:\/\/vetus.com\/wp-content\/uploads\/E-POD_full.png 1400w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                24 februari, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/e-pod\/\" class=\"stretched-link h5\">\n                E-POD            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-507x362.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-507x362.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-300x214.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-768x549.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-210x150.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-330x236.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-431x308.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-530x379.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-690x493.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-930x664.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1-1170x836.jpg 1170w, https:\/\/vetus.com\/wp-content\/uploads\/e-pod_e-line_voor_web_1400x1000-px-1.jpg 1400w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                23 februari, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/e-drives\/\" class=\"stretched-link h5\">\n                E-DRIVES            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-431x288.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-530x354.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-930x621.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_600hp_V12-VeradoBenMatthews-1130111_08-1170x781.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                16 februari, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release_mercury-marine\/\" class=\"stretched-link h5\">\n                Press Release &#8211; Mercury Marine\u00ae            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-507x338.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-530x354.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/MM_530-Scout_SW_Carolina_Quad-V12_600hp_S6A4812-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                16 februari, 2022                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/mercury-marine\/\" class=\"stretched-link h5\">\n                Mercury Marine\u00ae            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-507x338.jpg\" class=\"media__source img-fit\" alt=\"VETUS BOW PRO Sailing\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-507x338.jpg 507w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-210x140.jpg 210w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-330x220.jpg 330w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-431x287.jpg 431w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-530x353.jpg 530w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-690x460.jpg 690w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-930x620.jpg 930w, https:\/\/vetus.com\/wp-content\/uploads\/shutterstock_1188320323-1170x780.jpg 1170w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                10 december, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/the-bow-pro-thruster-family\/\" class=\"stretched-link h5\">\n                BOW PRO Thruster            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"362\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/001-507x362.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/001-507x362.png 507w, https:\/\/vetus.com\/wp-content\/uploads\/001-300x214.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/001-768x549.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/001-210x150.png 210w, https:\/\/vetus.com\/wp-content\/uploads\/001-330x236.png 330w, https:\/\/vetus.com\/wp-content\/uploads\/001-431x308.png 431w, https:\/\/vetus.com\/wp-content\/uploads\/001-530x379.png 530w, https:\/\/vetus.com\/wp-content\/uploads\/001-690x493.png 690w, https:\/\/vetus.com\/wp-content\/uploads\/001-930x664.png 930w, https:\/\/vetus.com\/wp-content\/uploads\/001-1170x836.png 1170w, https:\/\/vetus.com\/wp-content\/uploads\/001.png 1400w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                18 november, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-bow-pro-300-series\/\" class=\"stretched-link h5\">\n                Press release BOW PRO 300 Series            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_CAMPAIGN-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                10 mei, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/control-at-your-fingertips\/\" class=\"stretched-link h5\">\n                Control at your Fingertips            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_GEN_MRT_2021-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                4 maart, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-rc8-8\/\" class=\"stretched-link h5\">\n                Product of the Month March 2020            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB.png 1800w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-300x200.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-1024x683.png 1024w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-768x512.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-1536x1024.png 1536w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-418x279.png 418w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-604x403.png 604w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-970x647.png 970w, https:\/\/vetus.com\/wp-content\/uploads\/VCAN-FEB-1580x1053.png 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                18 februari, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/press-release-vetus-certified-as-first-thurster-integrator-for-nmea-2000\/\" class=\"stretched-link h5\">\n                Press release: VETUS certified as first Thruster Integrator for NMEA 2000            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT.png 1800w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-300x200.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-1024x683.png 1024w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-768x512.png 768w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-1536x1024.png 1536w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-418x279.png 418w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-604x403.png 604w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-970x647.png 970w, https:\/\/vetus.com\/wp-content\/uploads\/3D-PRINT-1580x1053.png 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                10 februari, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/creation-and-innovation-with-3d-printing\/\" class=\"stretched-link h5\">\n                Creation and innovation with 3D printing            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_EPOD_FEB_2021-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 februari, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-february-2021\/\" class=\"stretched-link h5\">\n                Product of the month February 2021            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_MAX_48V-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                25 januari, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/48v-is-now-available-for-the-maxwell-ps-range\/\" class=\"stretched-link h5\">\n                48V is now available for the Maxwell P&#038;S range            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_VDOCK_JAN_2021-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                4 januari, 2021                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-v-docker\/\" class=\"stretched-link h5\">\n                Product of the month V-Docker            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_DEC_2020-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 december, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-december-2020-the-e-line\/\" class=\"stretched-link h5\">\n                Product of the month December 2020: the E-Line            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_RC12_NOV_2020-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                4 november, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-november-2020\/\" class=\"stretched-link h5\">\n                Product of the month November 2020            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_ELINE_OKT_2020-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 oktober, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-launches-the-e-line\/\" class=\"stretched-link h5\">\n                VETUS launches the E-Line            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"338\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020.jpg 1800w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-300x200.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-1024x683.jpg 1024w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-768x512.jpg 768w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-1536x1024.jpg 1536w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-418x279.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-604x403.jpg 604w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-970x647.jpg 970w, https:\/\/vetus.com\/wp-content\/uploads\/News_Banners_BOWPRO_OKT_2020-1580x1053.jpg 1580w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                2 oktober, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-october-2020-the-bow-pro\/\" class=\"stretched-link h5\">\n                Product of the month October 2020: the BOW PRO            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"285\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/9-sept-2020.png\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/9-sept-2020.png 758w, https:\/\/vetus.com\/wp-content\/uploads\/9-sept-2020-300x169.png 300w, https:\/\/vetus.com\/wp-content\/uploads\/9-sept-2020-418x235.png 418w, https:\/\/vetus.com\/wp-content\/uploads\/9-sept-2020-604x339.png 604w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                9 september, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-launches-virtual-boat-show\/\" class=\"stretched-link h5\">\n                VETUS launches virtual boat show            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"331\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/1-sept-2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/1-sept-2020.jpg 658w, https:\/\/vetus.com\/wp-content\/uploads\/1-sept-2020-300x196.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/1-sept-2020-418x273.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/1-sept-2020-604x395.jpg 604w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                1 september, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/product-of-the-month-m-line-engines\/\" class=\"stretched-link h5\">\n                Product of the month M-Line Engines            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"241\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/28-jul-2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/28-jul-2020.jpg 758w, https:\/\/vetus.com\/wp-content\/uploads\/28-jul-2020-300x143.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/28-jul-2020-418x199.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/28-jul-2020-604x288.jpg 604w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                28 juli, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-is-proud-to-present-our-new-sup-brand-yellowv\/\" class=\"stretched-link h5\">\n                VETUS is proud to present our new sup brand: Yellow V            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"299\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/15954148051271827475.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/15954148051271827475.jpg 729w, https:\/\/vetus.com\/wp-content\/uploads\/15954148051271827475-300x177.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/15954148051271827475-418x247.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/15954148051271827475-604x356.jpg 604w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                22 juli, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/vetus-sailing-team-competing-in-maristo-cup\/\" class=\"stretched-link h5\">\n                VETUS sailing team competing in &#8220;Maristo Cup&#8221;            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                            <div class=\"col-12 col-md-4\">\n                            <div class=\"card card--default\">\n    <div class=\"card__header\">\n        <div class=\"card__media media ratio\">\n            <div class=\"media__wrapper\">\n                                    <img decoding=\"async\" width=\"507\" height=\"331\" src=\"https:\/\/vetus.com\/wp-content\/uploads\/14-juli-2020.jpg\" class=\"media__source img-fit\" alt=\"\" srcset=\"https:\/\/vetus.com\/wp-content\/uploads\/14-juli-2020.jpg 658w, https:\/\/vetus.com\/wp-content\/uploads\/14-juli-2020-300x196.jpg 300w, https:\/\/vetus.com\/wp-content\/uploads\/14-juli-2020-418x273.jpg 418w, https:\/\/vetus.com\/wp-content\/uploads\/14-juli-2020-604x395.jpg 604w\" sizes=\"auto, (max-width: 575.98px) 150px, (max-width: 767.98px) 150px, (max-width: 991.98px) 210px, (max-width: 1279.98px) 330px, (max-width: 1899.98px) 431px, 507px\" loading=\"lazy\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"card__body\">\n        <div class=\"card__label\">\n            <span>\n                14 juli, 2020                            <\/span>\n        <\/div>\n        <div class=\"card__title\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/new-emea-sales-and-global-marketing-director\/\" class=\"stretched-link h5\">\n                New Emea sales and global marketing director            <\/a>\n        <\/div>\n    <\/div>\n<\/div>                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"section__footer text-center d-block d-md-none mt-4\">\n            <a href=\"https:\/\/vetus.com\/nl\/nieuws\/\" class=\"btn btn-sm btn-empty btn-empty-primary\">\n                <span>\n                    Laatste nieuws                <\/span>\n                <i class=\"icon icon-keyboard_arrow_right\"><\/i>\n            <\/a>\n        <\/div>\n    <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":0,"menu_order":388,"comment_status":"closed","ping_status":"closed","template":"tpl-inverted.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2863","page","type-page","status-publish","hentry"],"acf":{"title":"In-house <br>Onderzoek & Ontwikkeling","introduction":"Ieder jaar lanceert VETUS revolutionaire innovaties, <br>ontwikkeld door ons eigen team van ingenieurs.","button":"","person":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Innovatie - VETUS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovatie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/\" \/>\n<meta property=\"og:site_name\" content=\"VETUS\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-22T12:44:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetus.com\\\/nl\\\/innovatie-bij-vetus\\\/\",\"url\":\"https:\\\/\\\/vetus.com\\\/nl\\\/innovatie-bij-vetus\\\/\",\"name\":\"Innovatie - VETUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetus.com\\\/nl\\\/#website\"},\"datePublished\":\"2021-03-11T11:55:12+00:00\",\"dateModified\":\"2022-03-22T12:44:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetus.com\\\/nl\\\/innovatie-bij-vetus\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vetus.com\\\/nl\\\/innovatie-bij-vetus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetus.com\\\/nl\\\/innovatie-bij-vetus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vetus.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetus.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/vetus.com\\\/nl\\\/\",\"name\":\"VETUS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetus.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Innovatie - VETUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/","og_locale":"nl_NL","og_type":"article","og_title":"Innovatie","og_url":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/","og_site_name":"VETUS","article_modified_time":"2022-03-22T12:44:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/","url":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/","name":"Innovatie - VETUS","isPartOf":{"@id":"https:\/\/vetus.com\/nl\/#website"},"datePublished":"2021-03-11T11:55:12+00:00","dateModified":"2022-03-22T12:44:56+00:00","breadcrumb":{"@id":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vetus.com\/nl\/innovatie-bij-vetus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vetus.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Innovatie"}]},{"@type":"WebSite","@id":"https:\/\/vetus.com\/nl\/#website","url":"https:\/\/vetus.com\/nl\/","name":"VETUS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetus.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/pages\/2863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/comments?post=2863"}],"version-history":[{"count":0,"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/pages\/2863\/revisions"}],"wp:attachment":[{"href":"https:\/\/vetus.com\/nl\/wp-json\/wp\/v2\/media?parent=2863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}